{"id":10611,"date":"2023-06-09T14:15:16","date_gmt":"2023-06-09T12:15:16","guid":{"rendered":"https:\/\/eu.camsrecycling.com\/sin-categorizar\/serie-uts-frantumatori-trasportabili\/"},"modified":"2025-09-24T11:15:36","modified_gmt":"2025-09-24T09:15:36","slug":"serie-uts-frantumatori-trasportabili","status":"publish","type":"post","link":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/","title":{"rendered":"Descubra las trituradoras de la serie UTS: la portabilidad como valor a\u00f1adido"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En la amplia gama de maquinaria para la trituraci\u00f3n y el reciclaje de inertes que ofrece CAMS, destacan sin duda las <\/span><b>plantas estacionarias transportables de la Serie UTS.<\/b><span style=\"font-weight: 400;\"> De hecho, las trituradoras transportables de la Serie UTS representan la soluci\u00f3n ideal para la trituraci\u00f3n y el reciclaje de inertes, escombros, asfalto y otros materiales, <\/span><b>aprovechando el mismo triturador en m\u00faltiples instalaciones<\/b><span style=\"font-weight: 400;\">. <\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Caracter\u00edsticas:<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Estas trituradoras se distinguen por dos sistemas patentados:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El primer sistema permite sustituir r\u00e1pidamente y con facilidad los dientes de los discos fresadores, haciendo que el <\/span><b>proceso de trituraci\u00f3n sea m\u00e1s eficiente<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El segundo sistema permite regular hidr\u00e1ulicamente la granulometr\u00eda del material de salida, ofreciendo la <\/span><b>posibilidad de obtener diferentes tama\u00f1os de fragmentos<\/b><span style=\"font-weight: 400;\"> seg\u00fan las necesidades espec\u00edficas.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2577 aligncenter\" src=\"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-300x200.jpg\" alt=\"\" width=\"605\" height=\"403\" srcset=\"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-300x200.jpg 300w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-1024x683.jpg 1024w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-768x512.jpg 768w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-1536x1024.jpg 1536w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-219x146.jpg 219w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-50x33.jpg 50w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6-113x75.jpg 113w, https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/uts-fotoslider6.jpg 1920w\" sizes=\"auto, (max-width:767px) 480px, 605px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La serie UTS ofrece:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Programas autom\u00e1ticos para la trituraci\u00f3n de distintos materiales<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Capacidad para procesar materiales h\u00famedos<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Transporte en formato compacto<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Alta resistencia al desgaste<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Alimentaci\u00f3n el\u00e9ctrica<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Baja contaminaci\u00f3n ac\u00fastica y menores emisiones<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, estas plantas est\u00e1n <\/span><b>totalmente automatizadas y pueden ser gestionadas por un solo operario mediante control remoto<\/b><span style=\"font-weight: 400;\">, reduciendo as\u00ed la necesidad de mano de obra para su funcionamiento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Otra caracter\u00edstica de las trituradoras transportables de la Serie UTS es la excelente <\/span><b>relaci\u00f3n entre consumo energ\u00e9tico y productividad<\/b><span style=\"font-weight: 400;\">: pese al bajo consumo de energ\u00eda, estas plantas son capaces de <\/span><b>garantizar altas prestaciones<\/b><span style=\"font-weight: 400;\"> y producir una cantidad significativa de material en poco tiempo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Transportabilidad: el valor a\u00f1adido de la serie UTS<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de su facilidad de uso, las plantas de la serie UTS son <\/span><b>extremadamente compactas y f\u00e1ciles de trasladar de una obra a otra<\/b><span style=\"font-weight: 400;\">. Esta caracter\u00edstica las hace <\/span><b>sumamente vers\u00e1tiles<\/b><span style=\"font-weight: 400;\"> y aptas para emplearse en diferentes contextos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La posibilidad de trasladar f\u00e1cilmente la trituradora de una obra a otra permite adaptarse a las necesidades espec\u00edficas de distintos lugares de trabajo. Esta flexibilidad es especialmente importante en el sector de la construcci\u00f3n y del reciclaje, donde los materiales a triturar pueden estar presentes en ubicaciones diversas. La <\/span><b>posibilidad de colocar la trituradora cerca de los materiales a triturar<\/b><span style=\"font-weight: 400;\"> reduce la necesidad de transportar los materiales a largas distancias. Esto conlleva un <\/span><b>ahorro de tiempo y una mayor eficiencia operativa global.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El hecho de que la maquinaria sea transportable de forma aut\u00f3noma permite ahorrar tiempo y dinero, al eliminar la necesidad de servicios de alquiler o de transporte especializado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por \u00faltimo, la r\u00e1pida instalaci\u00f3n y puesta en marcha de la trituradora transportable reduce los tiempos de inactividad, un factor especialmente ventajoso en situaciones en las que el tiempo es cr\u00edtico y se requiere un inicio r\u00e1pido de la operaci\u00f3n de trituraci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La capacidad de trasladar la trituradora a diferentes \u00e1reas permite <\/span><b>llegar a un p\u00fablico m\u00e1s amplio y ofrecer servicios de trituraci\u00f3n y reciclaje en distintas zonas.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Gracias a su automatizaci\u00f3n, compacidad, facilidad de uso y altas prestaciones, las trituradoras transportables de la Serie UTS representan una soluci\u00f3n eficaz para el procesamiento de inertes, escombros y otros materiales.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"color: #007a60; text-align: center;\"><strong>Cams: IL FUTURO \u00e8 VERDE<\/strong><\/p>\n<div><\/div>\n<div style=\"text-align: center;\"><div class=\"button_align align_center\"><a class=\"button  button_size_2\" href=\"https:\/\/eu.camsrecycling.com\/es\/contactos\/\"     style=\"background-color:#007a60!important;color:#fff;\"     title=\"\"><span class=\"button_label\">Cont\u00e1ctanos<\/span><\/a><\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En la amplia gama de maquinaria para la trituraci\u00f3n y el reciclaje de inertes que ofrece CAMS, destacan sin duda las plantas estacionarias transportables de la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":10612,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[132],"class_list":["post-10611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anuncios","tag-impianti-personalizzati-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trituradoras transportables serie UTS<\/title>\n<meta name=\"description\" content=\"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trituradoras transportables serie UTS\" \/>\n<meta property=\"og:description\" content=\"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/\" \/>\n<meta property=\"og:site_name\" content=\"CAMS\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-09T12:15:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T09:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"1265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/#\\\/schema\\\/person\\\/a29bcfcf0c06eff38e51672710ba68d9\"},\"headline\":\"Descubra las trituradoras de la serie UTS: la portabilidad como valor a\u00f1adido\",\"datePublished\":\"2023-06-09T12:15:16+00:00\",\"dateModified\":\"2025-09-24T09:15:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/\"},\"wordCount\":576,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.camsrecycling.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Copertina-per-Wordpress-articoli-cams-1.jpg\",\"keywords\":[\"impianti personalizzati\"],\"articleSection\":[\"Anuncios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/\",\"url\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/\",\"name\":\"Trituradoras transportables serie UTS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.camsrecycling.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Copertina-per-Wordpress-articoli-cams-1.jpg\",\"datePublished\":\"2023-06-09T12:15:16+00:00\",\"dateModified\":\"2025-09-24T09:15:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/#\\\/schema\\\/person\\\/a29bcfcf0c06eff38e51672710ba68d9\"},\"description\":\"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.camsrecycling.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Copertina-per-Wordpress-articoli-cams-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.camsrecycling.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Copertina-per-Wordpress-articoli-cams-1.jpg\",\"width\":1290,\"height\":1265},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/anuncios\\\/serie-uts-frantumatori-trasportabili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubra las trituradoras de la serie UTS: la portabilidad como valor a\u00f1adido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/\",\"name\":\"CAMS\",\"description\":\"IL FUTURO \u00c8 VERDE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.camsrecycling.com\\\/es\\\/#\\\/schema\\\/person\\\/a29bcfcf0c06eff38e51672710ba68d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/blog.camssrl.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trituradoras transportables serie UTS","description":"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/","og_locale":"es_ES","og_type":"article","og_title":"Trituradoras transportables serie UTS","og_description":"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.","og_url":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/","og_site_name":"CAMS","article_published_time":"2023-06-09T12:15:16+00:00","article_modified_time":"2025-09-24T09:15:36+00:00","og_image":[{"width":1290,"height":1265,"url":"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#article","isPartOf":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/"},"author":{"name":"admin","@id":"https:\/\/eu.camsrecycling.com\/es\/#\/schema\/person\/a29bcfcf0c06eff38e51672710ba68d9"},"headline":"Descubra las trituradoras de la serie UTS: la portabilidad como valor a\u00f1adido","datePublished":"2023-06-09T12:15:16+00:00","dateModified":"2025-09-24T09:15:36+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/"},"wordCount":576,"commentCount":0,"image":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg","keywords":["impianti personalizzati"],"articleSection":["Anuncios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/","url":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/","name":"Trituradoras transportables serie UTS","isPartOf":{"@id":"https:\/\/eu.camsrecycling.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#primaryimage"},"image":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg","datePublished":"2023-06-09T12:15:16+00:00","dateModified":"2025-09-24T09:15:36+00:00","author":{"@id":"https:\/\/eu.camsrecycling.com\/es\/#\/schema\/person\/a29bcfcf0c06eff38e51672710ba68d9"},"description":"Descubra las trituradoras de la serie UTS: la soluci\u00f3n ideal para triturar y reciclar \u00e1ridos y asfalto utilizando la misma m\u00e1quina en varias plantas.","breadcrumb":{"@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#primaryimage","url":"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg","contentUrl":"https:\/\/eu.camsrecycling.com\/wp-content\/uploads\/2023\/06\/Copertina-per-Wordpress-articoli-cams-1.jpg","width":1290,"height":1265},{"@type":"BreadcrumbList","@id":"https:\/\/eu.camsrecycling.com\/es\/anuncios\/serie-uts-frantumatori-trasportabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.camsrecycling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descubra las trituradoras de la serie UTS: la portabilidad como valor a\u00f1adido"}]},{"@type":"WebSite","@id":"https:\/\/eu.camsrecycling.com\/es\/#website","url":"https:\/\/eu.camsrecycling.com\/es\/","name":"CAMS","description":"IL FUTURO \u00c8 VERDE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.camsrecycling.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eu.camsrecycling.com\/es\/#\/schema\/person\/a29bcfcf0c06eff38e51672710ba68d9","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a1858dcc2493e5523b22d638bf66c34c3255cf6ebf31add0e941088dd6fcc3a?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/blog.camssrl.it"]}]}},"_links":{"self":[{"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/posts\/10611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/comments?post=10611"}],"version-history":[{"count":2,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/posts\/10611\/revisions"}],"predecessor-version":[{"id":10618,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/posts\/10611\/revisions\/10618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/media\/10612"}],"wp:attachment":[{"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/media?parent=10611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/categories?post=10611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.camsrecycling.com\/es\/wp-json\/wp\/v2\/tags?post=10611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}